{"id":3056,"date":"2019-03-15T10:21:44","date_gmt":"2019-03-15T13:21:44","guid":{"rendered":"http:\/\/webserver4.fumep.edu.br\/eep50anos\/?p=3056"},"modified":"2019-04-12T10:14:32","modified_gmt":"2019-04-12T13:14:32","slug":"as-comemoracoes-pelo-jubileu-de-ouro-da-eep","status":"publish","type":"post","link":"https:\/\/webserver4.fumep.edu.br\/eep50anos\/2019\/03\/15\/as-comemoracoes-pelo-jubileu-de-ouro-da-eep\/","title":{"rendered":"As comemora\u00e7\u00f5es pelo jubileu de ouro da EEP"},"content":{"rendered":"<h4>Encontro solene e exibi\u00e7\u00e3o de document\u00e1rio s\u00e3o alguns dos destaques<\/h4>\n<p>Por Gazeta de Piracicaba em 15\/03\/2019<\/p>\n<hr \/>\n<p>A Escola de Engenharia de Piracicaba (EEP) completa 50 anos e, a partir das 19h30 desta sexta-feira (15), recebe autoridades, alunos, funcion\u00e1rios, professores e convidados para a solenidade de seu Jubileu de Ouro. O evento ser\u00e1 realizado no Sal\u00e3o Nobre da Institui\u00e7\u00e3o. Na programa\u00e7\u00e3o, pronunciamento de autoridades e dirigentes, exibi\u00e7\u00e3o de document\u00e1rio hist\u00f3rico, homenagens a personalidades que contribu\u00edram para a proje\u00e7\u00e3o da Escola e coquetel de confraterniza\u00e7\u00e3o.<\/p>\n<p>O presidente da Comiss\u00e3o dos 50 Anos, professor Milton Rontani, lembrou que as comemora\u00e7\u00f5es tiveram in\u00edcio em janeiro com solenidades de formaturas, prosseguiu em fevereiro com a aula inaugural, abriu o m\u00eas de mar\u00e7o com a Exposi\u00e7\u00e3o &#8216;Pira Cartoon&#8217; no Espa\u00e7o Cultural da Biblioteca, e ter\u00e1 continuidade durante todo o ano com uma s\u00e9rie de atividades.<\/p>\n<p>\u201cTeremos, ainda, a inaugura\u00e7\u00e3o da Pra\u00e7a do Jubileu, sess\u00e3o solene na C\u00e2mara, competi\u00e7\u00f5es esportivas, Corrida dos 50 Anos, palestra solene no Teatro Municipal, Encontro de Pais &#8211; &#8217;50 Anos em Fam\u00edlia&#8217; e jantar de gala para os colaboradores\u201d, disse Rontani.<\/p>\n<p>Segundo ele, eventos de peso para a Escola tamb\u00e9m compor\u00e3o as comemora\u00e7\u00f5es, a exemplo da Engetec, Competi\u00e7\u00e3o Baja SAE Regional na EEP, Encontro de Carros Antigos, Maratona de Programa\u00e7\u00e3o, Concurso Pontes de Macarr\u00e3o, Semana das Engenharias Civil e Ambiental, Jornada de Administra\u00e7\u00e3o, Projetos Mecatr\u00f4nicos e Competi\u00e7\u00e3o de Aerobarcos.<\/p>\n<p>Ao enaltecer a proje\u00e7\u00e3o da EEP, o diretor-acad\u00eamico, professor Jos\u00e9 Carlos Chitolina, revelou que quando tudo come\u00e7ou, em 1969, a EEP se resumia a um Bloco Acad\u00eamico inserido em um terreno gigantesco, de 240 mil m2, nos altos da avenida Monsenhor Martinho Salgot, que ainda nem era pavimentada. Cinco d\u00e9cadas depois, a Escola ganhou notoriedade e reconhecimento p\u00fablico pelo ensino de qualidade que oferece.<\/p>\n<p>De l\u00e1, sa\u00edram cerca de 6.850 alunos desde a cria\u00e7\u00e3o do primeiro curso &#8211; Engenharia Civil. A Escola oferece tamb\u00e9m nove cursos de p\u00f3s-gradua\u00e7\u00e3o, desempenhando papel estrat\u00e9gico na forma\u00e7\u00e3o de profissionais altamente capacitados para liderar e aprofundar discuss\u00f5es de forma realista e harmoniosa, garantindo sustenta\u00e7\u00e3o e respaldo t\u00e9cnico em atendimento \u00e0s reais necessidades do setor produtivo e da comunidade; revelando o comprometimento da Escola com as transforma\u00e7\u00f5es sociais.<\/p>\n<p>Para o diretor-executivo da Fumep, professor Ant\u00f4nio Carlos Copatto, a infraestrutura consolidada nestas cinco d\u00e9cadas e o ambiente proporcionado aos alunos por ampla Biblioteca, modernos Laborat\u00f3rios, Anfiteatros, Sal\u00e3o Nobre, Centro de Conviv\u00eancia e de Lazer, quadras poliesportivas, campos de futebol, pista de caminhada, pista de competi\u00e7\u00e3o baja, academia ao ar livre, pra\u00e7a de alimenta\u00e7\u00e3o, estacionamento e muita \u00e1rea verde, complementam o aprendizado.<\/p>\n<p>Fonte: <a href=\"http:\/\/www.gazetadepiracicaba.com.br\/_conteudo\/2019\/03\/canais\/piracicaba_e_regiao\/651363-as-comemoracoes-pelo-jubileu-de-ouro-da-eep.html\" target=\"_blank\" rel=\"noopener noreferrer\">Gazeta de Piracicaba<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Encontro solene e exibi\u00e7\u00e3o de document\u00e1rio s\u00e3o alguns dos destaques Por Gazeta de Piracicaba em 15\/03\/2019 A Escola de Engenharia de Piracicaba (EEP) completa 50 anos e, a partir das 19h30 desta sexta-feira (15), recebe autoridades, alunos, funcion\u00e1rios, professores e convidados para a solenidade de seu Jubileu de Ouro. O evento ser\u00e1 realizado no Sal\u00e3o [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":3061,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[366],"tags":[],"class_list":["post-3056","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fatos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>As comemora\u00e7\u00f5es pelo jubileu de ouro da EEP - EEP 50 Anos<\/title>\n<meta name=\"description\" content=\"Encontro solene e exibi\u00e7\u00e3o de document\u00e1rio s\u00e3o alguns dos destaques. A Escola de Engenharia de Piracicaba (EEP) completa 50 anos e, a partir das 19h30 desta sexta-feira (15), recebe autoridades, alunos, funcion\u00e1rios, professores e convidados para a solenidade de seu Jubileu de Ouro.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/webserver4.fumep.edu.br\/eep50anos\/2019\/03\/15\/as-comemoracoes-pelo-jubileu-de-ouro-da-eep\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"As comemora\u00e7\u00f5es pelo jubileu de ouro da EEP - EEP 50 Anos\" \/>\n<meta property=\"og:description\" content=\"Encontro solene e exibi\u00e7\u00e3o de document\u00e1rio s\u00e3o alguns dos destaques. A Escola de Engenharia de Piracicaba (EEP) completa 50 anos e, a partir das 19h30 desta sexta-feira (15), recebe autoridades, alunos, funcion\u00e1rios, professores e convidados para a solenidade de seu Jubileu de Ouro.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/webserver4.fumep.edu.br\/eep50anos\/2019\/03\/15\/as-comemoracoes-pelo-jubileu-de-ouro-da-eep\/\" \/>\n<meta property=\"og:site_name\" content=\"EEP 50 Anos\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-15T13:21:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-12T13:14:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/webserver4.fumep.edu.br\/eep50anos\/site\/wp-content\/uploads\/2019\/04\/sessaosolene_eep50anos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"998\" \/>\n\t<meta property=\"og:image:height\" content=\"663\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eep50anos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eep50anos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/webserver4.fumep.edu.br\/eep50anos\/2019\/03\/15\/as-comemoracoes-pelo-jubileu-de-ouro-da-eep\/\",\"url\":\"https:\/\/webserver4.fumep.edu.br\/eep50anos\/2019\/03\/15\/as-comemoracoes-pelo-jubileu-de-ouro-da-eep\/\",\"name\":\"As comemora\u00e7\u00f5es pelo jubileu de ouro da EEP - EEP 50 Anos\",\"isPartOf\":{\"@id\":\"https:\/\/webserver4.fumep.edu.br\/eep50anos\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/webserver4.fumep.edu.br\/eep50anos\/2019\/03\/15\/as-comemoracoes-pelo-jubileu-de-ouro-da-eep\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/webserver4.fumep.edu.br\/eep50anos\/2019\/03\/15\/as-comemoracoes-pelo-jubileu-de-ouro-da-eep\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/webserver4.fumep.edu.br\/eep50anos\/site\/wp-content\/uploads\/2019\/04\/sessaosolene_eep50anos.jpg\",\"datePublished\":\"2019-03-15T13:21:44+00:00\",\"dateModified\":\"2019-04-12T13:14:32+00:00\",\"author\":{\"@id\":\"https:\/\/webserver4.fumep.edu.br\/eep50anos\/#\/schema\/person\/c0f5a3ee772d81e2731f58bd7ee84f0d\"},\"description\":\"Encontro solene e exibi\u00e7\u00e3o de document\u00e1rio s\u00e3o alguns dos destaques. A Escola de Engenharia de Piracicaba (EEP) completa 50 anos e, a partir das 19h30 desta sexta-feira (15), recebe autoridades, alunos, funcion\u00e1rios, professores e convidados para a solenidade de seu Jubileu de Ouro.\",\"breadcrumb\":{\"@id\":\"https:\/\/webserver4.fumep.edu.br\/eep50anos\/2019\/03\/15\/as-comemoracoes-pelo-jubileu-de-ouro-da-eep\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/webserver4.fumep.edu.br\/eep50anos\/2019\/03\/15\/as-comemoracoes-pelo-jubileu-de-ouro-da-eep\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/webserver4.fumep.edu.br\/eep50anos\/2019\/03\/15\/as-comemoracoes-pelo-jubileu-de-ouro-da-eep\/#primaryimage\",\"url\":\"https:\/\/webserver4.fumep.edu.br\/eep50anos\/site\/wp-content\/uploads\/2019\/04\/sessaosolene_eep50anos.jpg\",\"contentUrl\":\"https:\/\/webserver4.fumep.edu.br\/eep50anos\/site\/wp-content\/uploads\/2019\/04\/sessaosolene_eep50anos.jpg\",\"width\":998,\"height\":663},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/webserver4.fumep.edu.br\/eep50anos\/2019\/03\/15\/as-comemoracoes-pelo-jubileu-de-ouro-da-eep\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/webserver4.fumep.edu.br\/eep50anos\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"As comemora\u00e7\u00f5es pelo jubileu de ouro da EEP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/webserver4.fumep.edu.br\/eep50anos\/#website\",\"url\":\"https:\/\/webserver4.fumep.edu.br\/eep50anos\/\",\"name\":\"EEP 50 Anos\",\"description\":\"Escola de Engenharia de Piracicaba\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/webserver4.fumep.edu.br\/eep50anos\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/webserver4.fumep.edu.br\/eep50anos\/#\/schema\/person\/c0f5a3ee772d81e2731f58bd7ee84f0d\",\"name\":\"Eep50anos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/webserver4.fumep.edu.br\/eep50anos\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f50be53baa78eea0af507d2954b86974?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f50be53baa78eea0af507d2954b86974?s=96&d=mm&r=g\",\"caption\":\"Eep50anos\"},\"url\":\"https:\/\/webserver4.fumep.edu.br\/eep50anos\/author\/eep50anos\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"As comemora\u00e7\u00f5es pelo jubileu de ouro da EEP - EEP 50 Anos","description":"Encontro solene e exibi\u00e7\u00e3o de document\u00e1rio s\u00e3o alguns dos destaques. A Escola de Engenharia de Piracicaba (EEP) completa 50 anos e, a partir das 19h30 desta sexta-feira (15), recebe autoridades, alunos, funcion\u00e1rios, professores e convidados para a solenidade de seu Jubileu de Ouro.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/webserver4.fumep.edu.br\/eep50anos\/2019\/03\/15\/as-comemoracoes-pelo-jubileu-de-ouro-da-eep\/","og_locale":"pt_BR","og_type":"article","og_title":"As comemora\u00e7\u00f5es pelo jubileu de ouro da EEP - EEP 50 Anos","og_description":"Encontro solene e exibi\u00e7\u00e3o de document\u00e1rio s\u00e3o alguns dos destaques. A Escola de Engenharia de Piracicaba (EEP) completa 50 anos e, a partir das 19h30 desta sexta-feira (15), recebe autoridades, alunos, funcion\u00e1rios, professores e convidados para a solenidade de seu Jubileu de Ouro.","og_url":"https:\/\/webserver4.fumep.edu.br\/eep50anos\/2019\/03\/15\/as-comemoracoes-pelo-jubileu-de-ouro-da-eep\/","og_site_name":"EEP 50 Anos","article_published_time":"2019-03-15T13:21:44+00:00","article_modified_time":"2019-04-12T13:14:32+00:00","og_image":[{"width":998,"height":663,"url":"https:\/\/webserver4.fumep.edu.br\/eep50anos\/site\/wp-content\/uploads\/2019\/04\/sessaosolene_eep50anos.jpg","type":"image\/jpeg"}],"author":"Eep50anos","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eep50anos","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/webserver4.fumep.edu.br\/eep50anos\/2019\/03\/15\/as-comemoracoes-pelo-jubileu-de-ouro-da-eep\/","url":"https:\/\/webserver4.fumep.edu.br\/eep50anos\/2019\/03\/15\/as-comemoracoes-pelo-jubileu-de-ouro-da-eep\/","name":"As comemora\u00e7\u00f5es pelo jubileu de ouro da EEP - EEP 50 Anos","isPartOf":{"@id":"https:\/\/webserver4.fumep.edu.br\/eep50anos\/#website"},"primaryImageOfPage":{"@id":"https:\/\/webserver4.fumep.edu.br\/eep50anos\/2019\/03\/15\/as-comemoracoes-pelo-jubileu-de-ouro-da-eep\/#primaryimage"},"image":{"@id":"https:\/\/webserver4.fumep.edu.br\/eep50anos\/2019\/03\/15\/as-comemoracoes-pelo-jubileu-de-ouro-da-eep\/#primaryimage"},"thumbnailUrl":"https:\/\/webserver4.fumep.edu.br\/eep50anos\/site\/wp-content\/uploads\/2019\/04\/sessaosolene_eep50anos.jpg","datePublished":"2019-03-15T13:21:44+00:00","dateModified":"2019-04-12T13:14:32+00:00","author":{"@id":"https:\/\/webserver4.fumep.edu.br\/eep50anos\/#\/schema\/person\/c0f5a3ee772d81e2731f58bd7ee84f0d"},"description":"Encontro solene e exibi\u00e7\u00e3o de document\u00e1rio s\u00e3o alguns dos destaques. A Escola de Engenharia de Piracicaba (EEP) completa 50 anos e, a partir das 19h30 desta sexta-feira (15), recebe autoridades, alunos, funcion\u00e1rios, professores e convidados para a solenidade de seu Jubileu de Ouro.","breadcrumb":{"@id":"https:\/\/webserver4.fumep.edu.br\/eep50anos\/2019\/03\/15\/as-comemoracoes-pelo-jubileu-de-ouro-da-eep\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/webserver4.fumep.edu.br\/eep50anos\/2019\/03\/15\/as-comemoracoes-pelo-jubileu-de-ouro-da-eep\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/webserver4.fumep.edu.br\/eep50anos\/2019\/03\/15\/as-comemoracoes-pelo-jubileu-de-ouro-da-eep\/#primaryimage","url":"https:\/\/webserver4.fumep.edu.br\/eep50anos\/site\/wp-content\/uploads\/2019\/04\/sessaosolene_eep50anos.jpg","contentUrl":"https:\/\/webserver4.fumep.edu.br\/eep50anos\/site\/wp-content\/uploads\/2019\/04\/sessaosolene_eep50anos.jpg","width":998,"height":663},{"@type":"BreadcrumbList","@id":"https:\/\/webserver4.fumep.edu.br\/eep50anos\/2019\/03\/15\/as-comemoracoes-pelo-jubileu-de-ouro-da-eep\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/webserver4.fumep.edu.br\/eep50anos\/"},{"@type":"ListItem","position":2,"name":"As comemora\u00e7\u00f5es pelo jubileu de ouro da EEP"}]},{"@type":"WebSite","@id":"https:\/\/webserver4.fumep.edu.br\/eep50anos\/#website","url":"https:\/\/webserver4.fumep.edu.br\/eep50anos\/","name":"EEP 50 Anos","description":"Escola de Engenharia de Piracicaba","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/webserver4.fumep.edu.br\/eep50anos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/webserver4.fumep.edu.br\/eep50anos\/#\/schema\/person\/c0f5a3ee772d81e2731f58bd7ee84f0d","name":"Eep50anos","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/webserver4.fumep.edu.br\/eep50anos\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f50be53baa78eea0af507d2954b86974?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f50be53baa78eea0af507d2954b86974?s=96&d=mm&r=g","caption":"Eep50anos"},"url":"https:\/\/webserver4.fumep.edu.br\/eep50anos\/author\/eep50anos\/"}]}},"_links":{"self":[{"href":"https:\/\/webserver4.fumep.edu.br\/eep50anos\/wp-json\/wp\/v2\/posts\/3056"}],"collection":[{"href":"https:\/\/webserver4.fumep.edu.br\/eep50anos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/webserver4.fumep.edu.br\/eep50anos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/webserver4.fumep.edu.br\/eep50anos\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/webserver4.fumep.edu.br\/eep50anos\/wp-json\/wp\/v2\/comments?post=3056"}],"version-history":[{"count":2,"href":"https:\/\/webserver4.fumep.edu.br\/eep50anos\/wp-json\/wp\/v2\/posts\/3056\/revisions"}],"predecessor-version":[{"id":3259,"href":"https:\/\/webserver4.fumep.edu.br\/eep50anos\/wp-json\/wp\/v2\/posts\/3056\/revisions\/3259"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/webserver4.fumep.edu.br\/eep50anos\/wp-json\/wp\/v2\/media\/3061"}],"wp:attachment":[{"href":"https:\/\/webserver4.fumep.edu.br\/eep50anos\/wp-json\/wp\/v2\/media?parent=3056"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/webserver4.fumep.edu.br\/eep50anos\/wp-json\/wp\/v2\/categories?post=3056"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/webserver4.fumep.edu.br\/eep50anos\/wp-json\/wp\/v2\/tags?post=3056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}